{"id":178,"count":1,"description":"","link":"https:\/\/www.es-eventos.com\/en\/category\/adventure\/","name":"Adventure","slug":"adventure","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adventure archivos - ES Eventos<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adventure archivos - ES Eventos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.es-eventos.com\/en\/category\/adventure\/\" \/>\n<meta property=\"og:site_name\" content=\"ES Eventos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adventure archivos - ES Eventos","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Adventure archivos - ES Eventos","og_url":"https:\/\/www.es-eventos.com\/en\/category\/adventure\/","og_site_name":"ES Eventos","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.es-eventos.com\/en\/category\/adventure\/","url":"https:\/\/www.es-eventos.com\/en\/category\/adventure\/","name":"Adventure archivos - ES Eventos","isPartOf":{"@id":"https:\/\/www.es-eventos.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.es-eventos.com\/en\/category\/adventure\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.es-eventos.com\/en\/category\/adventure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.es-eventos.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Adventure"}]},{"@type":"WebSite","@id":"https:\/\/www.es-eventos.com\/#website","url":"https:\/\/www.es-eventos.com\/","name":"ES Eventos","description":"Espacios \u00fanicos para momentos inolvidables","publisher":{"@id":"https:\/\/www.es-eventos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.es-eventos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.es-eventos.com\/#organization","name":"ES Eventos","url":"https:\/\/www.es-eventos.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.es-eventos.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.es-eventos.com\/wp-content\/uploads\/2021\/10\/logo_eseventos_black.png","contentUrl":"https:\/\/www.es-eventos.com\/wp-content\/uploads\/2021\/10\/logo_eseventos_black.png","width":2560,"height":655,"caption":"ES Eventos"},"image":{"@id":"https:\/\/www.es-eventos.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.es-eventos.com\/en\/wp-json\/wp\/v2\/categories\/178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.es-eventos.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.es-eventos.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.es-eventos.com\/en\/wp-json\/wp\/v2\/posts?categories=178"},{"href":"https:\/\/www.es-eventos.com\/en\/wp-json\/wp\/v2\/instalaciones?categories=178"},{"href":"https:\/\/www.es-eventos.com\/en\/wp-json\/wp\/v2\/tb_activities?categories=178"},{"href":"https:\/\/www.es-eventos.com\/en\/wp-json\/wp\/v2\/fiestas?categories=178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}